{"id":25,"count":0,"description":"","link":"https:\/\/salat.club\/licca\/category\/ishikawa\/","name":"\u77f3\u5ddd\u770c","slug":"ishikawa","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/salat.club\/licca\/wp-json\/wp\/v2\/categories\/25","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/salat.club\/licca\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/salat.club\/licca\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/salat.club\/licca\/wp-json\/wp\/v2\/posts?categories=25"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}