{"id":28,"count":0,"description":"","link":"https:\/\/salat.club\/licca\/category\/nagano\/","name":"\u9577\u91ce\u770c","slug":"nagano","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/salat.club\/licca\/wp-json\/wp\/v2\/categories\/28","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/salat.club\/licca\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/salat.club\/licca\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/salat.club\/licca\/wp-json\/wp\/v2\/posts?categories=28"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}